{"id":66734,"date":"2018-12-17T12:36:49","date_gmt":"2018-12-17T11:36:49","guid":{"rendered":"https:\/\/internetrepublica.com\/?p=66734"},"modified":"2018-12-19T12:34:29","modified_gmt":"2018-12-19T11:34:29","slug":"que-es-el-ctr","status":"publish","type":"post","link":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/","title":{"rendered":"CTR SEO qu\u00e9 es en Google y para que sirve"},"content":{"rendered":"<p><strong>\u00bfPero, qu\u00e9 es el CTR?<\/strong> La tasa de clics (CTR) es un concepto incre\u00edblemente importante en el marketing de buscadores. La definici\u00f3n m\u00e1s simple es que la tasa de clics es el porcentaje de personas que hacen clic en su anuncio despu\u00e9s de haberlo visto. (En t\u00e9rminos matem\u00e1ticos: CTR = Clicks\/Impressions.)<\/p>\n<h2>\u00bfCTR Seo q\u00fae es en Internet?<\/h2>\n<p>El CTR\u00a0(click through rate) es el porcentaje de click que un resultado recibe en el motor de b\u00fasqueda, partiendo de las impresiones que tenga.<\/p>\n<ul>\n<li>Calcular el <strong>CTR<\/strong>: click\/impresiones * 100=CTR<\/li>\n<li>CTR en <strong>Publicidad SEM<\/strong>: con AdWords, su CTR es uno de los componentes clave de su \u00edndice de calidad. En SEO, su CTR va a determinar si usted mantiene su ranking.<\/li>\n<li>CTR con <strong>SEO<\/strong>: SEO org\u00e1nico, su \u00e9xito puede ser mejorado con Clic bait, fragmentos enriquecidos, T\u00edtulos y meta-descripciones.<\/li>\n<\/ul>\n<h2>Objetivos del CTR<\/h2>\n<ol>\n<li>Conseguir que m\u00e1s personas vean tu anuncio o fragmento<\/li>\n<li>Conseguir que m\u00e1s personas hagan clic en tu anuncio o fragmento;<\/li>\n<li>Conseguir que m\u00e1s personas se conviertan en clientes (es decir, conversion) en tu p\u00e1gina de destino.<\/li>\n<\/ol>\n<p>En otras palabras, el marketing en buscadores es un &#8220;sistema restringido&#8221;. Y una de esas limitaciones es el CTR. B\u00e1sicamente, puedes pensar en Google (y m\u00e1s ampliamente, en todos los motores de b\u00fasqueda) como una democracia: la gente vota haciendo clic. As\u00ed que su CTR realmente determinar\u00e1 su \u00e9xito.<\/p>\n<p><a href=\"https:\/\/internetrepublica.com\">\u2705<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfPero, qu\u00e9 es el CTR? La tasa de clics (CTR) es un concepto incre\u00edblemente importante en el marketing de buscadores. La definici\u00f3n m\u00e1s simple es&#8230;<\/p>\n","protected":false},"author":67,"featured_media":66735,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","inline_featured_image":false,"footnotes":""},"categories":[1155],"tags":[],"class_list":["post-66734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diccionario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu\u00e9 es el CTR y como nos beneficia o penaliza<\/title>\n<meta name=\"description\" content=\"\u00bfPero, qu\u00e9 es el CTR? La tasa de clics (CTR) es un concepto incre\u00edblemente importante en el marketing de buscadores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 es el CTR y como nos beneficia o penaliza\" \/>\n<meta property=\"og:description\" content=\"\u00bfPero, qu\u00e9 es el CTR? La tasa de clics (CTR) es un concepto incre\u00edblemente importante en el marketing de buscadores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/\" \/>\n<meta property=\"og:site_name\" content=\"Internet Rep\u00fablica\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-17T11:36:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-19T11:34:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internetrepublica.com\/blog\/wp-content\/uploads\/2018\/12\/que-es-el-ctr.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1276\" \/>\n\t<meta property=\"og:image:height\" content=\"371\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ruben Cabra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ruben Cabra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/\"},\"author\":{\"name\":\"Ruben Cabra\",\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/#\\\/schema\\\/person\\\/3c0fc85704d712de40ecc6fa849c9544\"},\"headline\":\"CTR SEO qu\u00e9 es en Google y para que sirve\",\"datePublished\":\"2018-12-17T11:36:49+00:00\",\"dateModified\":\"2018-12-19T11:34:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/\"},\"wordCount\":252,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/que-es-el-ctr.png\",\"articleSection\":[\"Diccionario SEO\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/\",\"url\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/\",\"name\":\"Qu\u00e9 es el CTR y como nos beneficia o penaliza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/que-es-el-ctr.png\",\"datePublished\":\"2018-12-17T11:36:49+00:00\",\"dateModified\":\"2018-12-19T11:34:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/#\\\/schema\\\/person\\\/3c0fc85704d712de40ecc6fa849c9544\"},\"description\":\"\u00bfPero, qu\u00e9 es el CTR? La tasa de clics (CTR) es un concepto incre\u00edblemente importante en el marketing de buscadores.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/que-es-el-ctr.png\",\"contentUrl\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/que-es-el-ctr.png\",\"width\":1276,\"height\":371,\"caption\":\"CTR SEO factor importante\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Agencia Marketing Digital\",\"item\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEO\",\"item\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/seo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Diccionario SEO\",\"item\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/seo\\\/diccionario\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"CTR SEO qu\u00e9 es en Google y para que sirve\",\"item\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/que-es-el-ctr\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/\",\"name\":\"Internet Rep\u00fablica\",\"description\":\"Agencia SEO y Marketing Digital\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/#\\\/schema\\\/person\\\/3c0fc85704d712de40ecc6fa849c9544\",\"name\":\"Ruben Cabra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f9274233d6d40baafdc26a52dfa32c5aab04588ed91efe96aec470b314d371c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f9274233d6d40baafdc26a52dfa32c5aab04588ed91efe96aec470b314d371c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f9274233d6d40baafdc26a52dfa32c5aab04588ed91efe96aec470b314d371c?s=96&d=mm&r=g\",\"caption\":\"Ruben Cabra\"},\"description\":\"SEO &amp; IA Expert en Internet Rep\u00fablica. Apasionado por la tecnolog\u00eda y comprometido con ayudar a las empresas a prosperar en el mundo digital mediante estrategias avanzadas de SEO y soluciones innovadoras basadas en inteligencia artificial.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/rubn-cabra-zamora-681856119\\\/\"],\"url\":\"https:\\\/\\\/internetrepublica.com\\\/blog\\\/author\\\/ruben-cabra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e9 es el CTR y como nos beneficia o penaliza","description":"\u00bfPero, qu\u00e9 es el CTR? La tasa de clics (CTR) es un concepto incre\u00edblemente importante en el marketing de buscadores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 es el CTR y como nos beneficia o penaliza","og_description":"\u00bfPero, qu\u00e9 es el CTR? La tasa de clics (CTR) es un concepto incre\u00edblemente importante en el marketing de buscadores.","og_url":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/","og_site_name":"Internet Rep\u00fablica","article_published_time":"2018-12-17T11:36:49+00:00","article_modified_time":"2018-12-19T11:34:29+00:00","og_image":[{"width":1276,"height":371,"url":"https:\/\/internetrepublica.com\/blog\/wp-content\/uploads\/2018\/12\/que-es-el-ctr.png","type":"image\/png"}],"author":"Ruben Cabra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ruben Cabra","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/#article","isPartOf":{"@id":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/"},"author":{"name":"Ruben Cabra","@id":"https:\/\/internetrepublica.com\/blog\/#\/schema\/person\/3c0fc85704d712de40ecc6fa849c9544"},"headline":"CTR SEO qu\u00e9 es en Google y para que sirve","datePublished":"2018-12-17T11:36:49+00:00","dateModified":"2018-12-19T11:34:29+00:00","mainEntityOfPage":{"@id":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/"},"wordCount":252,"commentCount":0,"image":{"@id":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/#primaryimage"},"thumbnailUrl":"https:\/\/internetrepublica.com\/blog\/wp-content\/uploads\/2018\/12\/que-es-el-ctr.png","articleSection":["Diccionario SEO"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/","url":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/","name":"Qu\u00e9 es el CTR y como nos beneficia o penaliza","isPartOf":{"@id":"https:\/\/internetrepublica.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/#primaryimage"},"image":{"@id":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/#primaryimage"},"thumbnailUrl":"https:\/\/internetrepublica.com\/blog\/wp-content\/uploads\/2018\/12\/que-es-el-ctr.png","datePublished":"2018-12-17T11:36:49+00:00","dateModified":"2018-12-19T11:34:29+00:00","author":{"@id":"https:\/\/internetrepublica.com\/blog\/#\/schema\/person\/3c0fc85704d712de40ecc6fa849c9544"},"description":"\u00bfPero, qu\u00e9 es el CTR? La tasa de clics (CTR) es un concepto incre\u00edblemente importante en el marketing de buscadores.","breadcrumb":{"@id":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/#primaryimage","url":"https:\/\/internetrepublica.com\/blog\/wp-content\/uploads\/2018\/12\/que-es-el-ctr.png","contentUrl":"https:\/\/internetrepublica.com\/blog\/wp-content\/uploads\/2018\/12\/que-es-el-ctr.png","width":1276,"height":371,"caption":"CTR SEO factor importante"},{"@type":"BreadcrumbList","@id":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Agencia Marketing Digital","item":"https:\/\/internetrepublica.com\/blog\/"},{"@type":"ListItem","position":2,"name":"SEO","item":"https:\/\/internetrepublica.com\/blog\/seo\/"},{"@type":"ListItem","position":3,"name":"Diccionario SEO","item":"https:\/\/internetrepublica.com\/blog\/seo\/diccionario\/"},{"@type":"ListItem","position":4,"name":"CTR SEO qu\u00e9 es en Google y para que sirve","item":"https:\/\/internetrepublica.com\/blog\/que-es-el-ctr\/"}]},{"@type":"WebSite","@id":"https:\/\/internetrepublica.com\/blog\/#website","url":"https:\/\/internetrepublica.com\/blog\/","name":"Internet Rep\u00fablica","description":"Agencia SEO y Marketing Digital","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internetrepublica.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/internetrepublica.com\/blog\/#\/schema\/person\/3c0fc85704d712de40ecc6fa849c9544","name":"Ruben Cabra","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7f9274233d6d40baafdc26a52dfa32c5aab04588ed91efe96aec470b314d371c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f9274233d6d40baafdc26a52dfa32c5aab04588ed91efe96aec470b314d371c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f9274233d6d40baafdc26a52dfa32c5aab04588ed91efe96aec470b314d371c?s=96&d=mm&r=g","caption":"Ruben Cabra"},"description":"SEO &amp; IA Expert en Internet Rep\u00fablica. Apasionado por la tecnolog\u00eda y comprometido con ayudar a las empresas a prosperar en el mundo digital mediante estrategias avanzadas de SEO y soluciones innovadoras basadas en inteligencia artificial.","sameAs":["https:\/\/www.linkedin.com\/in\/rubn-cabra-zamora-681856119\/"],"url":"https:\/\/internetrepublica.com\/blog\/author\/ruben-cabra\/"}]}},"_links":{"self":[{"href":"https:\/\/internetrepublica.com\/blog\/wp-json\/wp\/v2\/posts\/66734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internetrepublica.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/internetrepublica.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/internetrepublica.com\/blog\/wp-json\/wp\/v2\/users\/67"}],"replies":[{"embeddable":true,"href":"https:\/\/internetrepublica.com\/blog\/wp-json\/wp\/v2\/comments?post=66734"}],"version-history":[{"count":3,"href":"https:\/\/internetrepublica.com\/blog\/wp-json\/wp\/v2\/posts\/66734\/revisions"}],"predecessor-version":[{"id":66780,"href":"https:\/\/internetrepublica.com\/blog\/wp-json\/wp\/v2\/posts\/66734\/revisions\/66780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internetrepublica.com\/blog\/wp-json\/wp\/v2\/media\/66735"}],"wp:attachment":[{"href":"https:\/\/internetrepublica.com\/blog\/wp-json\/wp\/v2\/media?parent=66734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/internetrepublica.com\/blog\/wp-json\/wp\/v2\/categories?post=66734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internetrepublica.com\/blog\/wp-json\/wp\/v2\/tags?post=66734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}